{"id":2015,"date":"2025-03-19T19:05:38","date_gmt":"2025-03-19T18:05:38","guid":{"rendered":"https:\/\/eligioielli.com\/?post_type=product&#038;p=2015"},"modified":"2025-06-07T16:20:12","modified_gmt":"2025-06-07T14:20:12","slug":"locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb","status":"publish","type":"product","link":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/","title":{"rendered":"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB"},"content":{"rendered":"<p>Movimento automatico SIO con rotore Blu Frecce Tricolori.<\/p>\n<p>Cassa 44mm in acciaio AISI 316L e titanio con trattamento PVD Blu.<\/p>\n<p>Quadrante con numeri arabi stampati personalizzato Frecce Tricolori.<\/p>\n<p>Vetro zaffiro anti-riflesso.<\/p>\n<p>Impermeabilit\u00e0 5 ATM.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Locman Orologio Uomo Frecce Tricolori Blu edizione limitata. Locman insieme a Frecce Tricolori Italia per celebrare l&#8217;aviazione Italiana.<\/p>\n<p>Movimento automatico SIO con rotore Blu Frecce Tricolori.<\/p>\n<p>Cassa 44mm in acciaio AISI 316L e titanio con trattamento PVD Blu.<\/p>\n<p>Quadrante con numeri arabi stampati personalizzato Frecce Tricolori.<\/p>\n<p>Vetro zaffiro anti-riflesso.<\/p>\n<p>Impermeabilit\u00e0 5 ATM.<\/p>\n","protected":false},"featured_media":2017,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[164],"product_cat":[163,31],"product_tag":[106,103,73,101,168,100,165,167,166,133],"class_list":{"0":"post-2015","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-locman","7":"product_cat-locman","8":"product_cat-orologi","9":"product_tag-anniversario","10":"product_tag-compleanno","11":"product_tag-eli-gioielli-orologi","12":"product_tag-festa-del-papa","13":"product_tag-frecce-tricolori","14":"product_tag-laurea","15":"product_tag-onomastico","16":"product_tag-orologio-automatico","17":"product_tag-orologio-uomo","18":"product_tag-ricorrenze","20":"first","21":"instock","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB - Eli Gioielli<\/title>\n<meta name=\"description\" content=\"Locman Orologio Uomo Frecce Tricolori Blu edizione limitata. Locman insieme a Frecce Tricolori Italia per celebrare l&#039;aviazione Italiana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB - Eli Gioielli\" \/>\n<meta property=\"og:description\" content=\"Locman Orologio Uomo Frecce Tricolori Blu edizione limitata. Locman insieme a Frecce Tricolori Italia per celebrare l&#039;aviazione Italiana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/\" \/>\n<meta property=\"og:site_name\" content=\"Eli Gioielli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Eligioiellimassa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-07T14:20:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/\",\"url\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/\",\"name\":\"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB - Eli Gioielli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eligioielli.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eligioielli.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0455B02S-BLFTBLPB-FRECCIE-BLU2.avif\",\"datePublished\":\"2025-03-19T18:05:38+00:00\",\"dateModified\":\"2025-06-07T14:20:12+00:00\",\"description\":\"Locman Orologio Uomo Frecce Tricolori Blu edizione limitata. Locman insieme a Frecce Tricolori Italia per celebrare l'aviazione Italiana.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eligioielli.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0455B02S-BLFTBLPB-FRECCIE-BLU2.avif\",\"contentUrl\":\"https:\\\/\\\/eligioielli.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0455B02S-BLFTBLPB-FRECCIE-BLU2.avif\",\"width\":1560,\"height\":2260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/product\\\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eligioielli.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/eligioielli.com\\\/index.php\\\/prodotti-eli-gioielli-massa-gioielleria-oreficeria\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eligioielli.com\\\/#website\",\"url\":\"https:\\\/\\\/eligioielli.com\\\/\",\"name\":\"Eli Gioielli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eligioielli.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eligioielli.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eligioielli.com\\\/#organization\",\"name\":\"Eli Gioielli\",\"url\":\"https:\\\/\\\/eligioielli.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/eligioielli.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eligioielli.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eligioielli.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo.png\",\"width\":165,\"height\":96,\"caption\":\"Eli Gioielli\"},\"image\":{\"@id\":\"https:\\\/\\\/eligioielli.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Eligioiellimassa\",\"https:\\\/\\\/www.instagram.com\\\/eli_gioielli\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB - Eli Gioielli","description":"Locman Orologio Uomo Frecce Tricolori Blu edizione limitata. Locman insieme a Frecce Tricolori Italia per celebrare l'aviazione Italiana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/","og_locale":"it_IT","og_type":"article","og_title":"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB - Eli Gioielli","og_description":"Locman Orologio Uomo Frecce Tricolori Blu edizione limitata. Locman insieme a Frecce Tricolori Italia per celebrare l'aviazione Italiana.","og_url":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/","og_site_name":"Eli Gioielli","article_publisher":"https:\/\/www.facebook.com\/Eligioiellimassa","article_modified_time":"2025-06-07T14:20:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/","url":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/","name":"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB - Eli Gioielli","isPartOf":{"@id":"https:\/\/eligioielli.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/#primaryimage"},"image":{"@id":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/#primaryimage"},"thumbnailUrl":"https:\/\/eligioielli.com\/wp-content\/uploads\/2025\/03\/0455B02S-BLFTBLPB-FRECCIE-BLU2.avif","datePublished":"2025-03-19T18:05:38+00:00","dateModified":"2025-06-07T14:20:12+00:00","description":"Locman Orologio Uomo Frecce Tricolori Blu edizione limitata. Locman insieme a Frecce Tricolori Italia per celebrare l'aviazione Italiana.","breadcrumb":{"@id":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/#primaryimage","url":"https:\/\/eligioielli.com\/wp-content\/uploads\/2025\/03\/0455B02S-BLFTBLPB-FRECCIE-BLU2.avif","contentUrl":"https:\/\/eligioielli.com\/wp-content\/uploads\/2025\/03\/0455B02S-BLFTBLPB-FRECCIE-BLU2.avif","width":1560,"height":2260},{"@type":"BreadcrumbList","@id":"https:\/\/eligioielli.com\/index.php\/product\/locman-orologio-uomo-frecce-tricolori-blu-edizione-limitata-cod-0455b02s-blftblpb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eligioielli.com\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/eligioielli.com\/index.php\/prodotti-eli-gioielli-massa-gioielleria-oreficeria\/"},{"@type":"ListItem","position":3,"name":"Orologio LOCMAN Uomo Frecce Tricolori Blu edizione limitata. Cod. 0455B02S-BLFTBLPB"}]},{"@type":"WebSite","@id":"https:\/\/eligioielli.com\/#website","url":"https:\/\/eligioielli.com\/","name":"Eli Gioielli","description":"","publisher":{"@id":"https:\/\/eligioielli.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eligioielli.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/eligioielli.com\/#organization","name":"Eli Gioielli","url":"https:\/\/eligioielli.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/eligioielli.com\/#\/schema\/logo\/image\/","url":"https:\/\/eligioielli.com\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/eligioielli.com\/wp-content\/uploads\/2024\/05\/logo.png","width":165,"height":96,"caption":"Eli Gioielli"},"image":{"@id":"https:\/\/eligioielli.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Eligioiellimassa","https:\/\/www.instagram.com\/eli_gioielli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/product\/2015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/comments?post=2015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/media\/2017"}],"wp:attachment":[{"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/media?parent=2015"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=2015"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=2015"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eligioielli.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=2015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}